{"id":44510,"date":"2020-07-13T17:21:12","date_gmt":"2020-07-13T17:21:12","guid":{"rendered":"https:\/\/quantocustaviajar.com\/blog\/?p=44510"},"modified":"2020-07-13T17:21:20","modified_gmt":"2020-07-13T17:21:20","slug":"voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles","status":"publish","type":"post","link":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/","title":{"rendered":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles"},"content":{"rendered":"\n<p>Seychelles \u00e9 um para\u00edso natural com diversas esp\u00e9cies end\u00eamicas de plantas e animais, que o tornam um lugar \u00fanico no mundo. Um dos principais exemplos \u00e9 o coco de mer, que se tornou um s\u00edmbolo do arquip\u00e9lago e seu formato curioso pode ser encontrado desde nos mais diferentes souvenirs at\u00e9 no carimbo da imigra\u00e7\u00e3o.<\/p>\n\n\n\n<p>O coco de mer s\u00f3 cresce naturalmente em dois lugares: na ilha de Praslin e na ilha Curieuse, ambas localizadas em Seychelles. Em Praslin, h\u00e1 a maior floresta intacta do coco de mer no mundo, dentro do Vall\u00e9e de Mai, casa de seis mil \u00e1rvores onde crescem os frutos. S\u00e3o palmeiras enormes, que chegam a mais de 30 metros de altura, com folhas de at\u00e9 10 metros de comprimento, que demoram d\u00e9cadas para crescer.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg\" alt=\"\" class=\"wp-image-44512\" srcset=\"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg 1020w, https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx-300x200.jpg 300w, https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx-768x512.jpg 768w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/figure><\/div>\n\n\n\n<p>O Vall\u00e9e de Mai \u00e9 tamb\u00e9m o s\u00edtio original do Jardim do \u00c9den, de acordo com uma lenda datada de 1881, criada pelo General Charles Gordon. Depois de milh\u00f5es de anos isolada, as esp\u00e9cies nesta floresta foram evoluindo de tal maneira que n\u00e3o s\u00e3o encontradas em nenhum outro lugar. Em 1966, o governo a declarou Reserva Natural e em 1983 foi reconhecida como um Patrim\u00f4nio da Humanidade pela UNESCO. Atualmente, a \u00e1rea \u00e9 gerenciada e protegida pela Seychelles Island Foundation.<\/p>\n\n\n\n<p>O coco de mer \u00e9 a maior semente do mundo, podendo chegar a mais de 30 cm de di\u00e2metro e 25 Kg. Seu nome significa \u201ccoco do mar\u201d, dado que em s\u00e9culos passados marinheiros europeus viam as sementes boiando e acreditavam que elas cresciam dentro dos oceanos. A semente tem um formato bastante diferente, que parecem n\u00e1degas, o que gera curiosidade de todos que a conhecem ao vivo. Inclusive, a planta tem tanto sua <strong>vers\u00e3o feminina, mais famosa em formato de n\u00e1degas, como sua vers\u00e3o masculina, mais comprida e tamb\u00e9m com um formato bastante sugestivo<\/strong>, o que ajuda a alimentar a lenda do fruto proibido no Jardim do \u00c9den em Seychelles.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"658\" height=\"983\" src=\"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG6-Male-Coco-de-Mer-bx.jpg\" alt=\"\" class=\"wp-image-44511\" srcset=\"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG6-Male-Coco-de-Mer-bx.jpg 658w, https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG6-Male-Coco-de-Mer-bx-201x300.jpg 201w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><\/figure><\/div>\n\n\n\n<p>O coco de mer, por ser uma esp\u00e9cie amea\u00e7ada, \u00e9 muito protegido em Seychelles e \u00e9 proibido retirar os frutos das palmeiras onde crescem. Os que caem das \u00e1rvores s\u00e3o recolhidos e recebem um selo do governo. \u00c9<strong> poss\u00edvel adquirir um coco como souvenir mediante o pagamento de algumas centenas de euros<\/strong> e apenas se ele vier com o selo e um certificado de exporta\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Para saber mais sobre o Vall\u00e9e de Mai, acesse\u00a0<a href=\"http:\/\/www.sif.sc\/vdm\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">www.sif.sc\/vdm<\/a>.<\/strong><\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre Seychelles, acesse\u00a0<a rel=\"noreferrer noopener\" href=\"http:\/\/www.visiteseychelles.com\/#_blank\" target=\"_blank\">www.visiteseychelles.com<\/a>\u00a0e o site\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"http:\/\/www.globalvisionaccess.com\/\" target=\"_blank\">www.globalvisionaccess.com<\/a>.<\/p>\n\n\n\n<p><em>Fotos e texto enviados por  Global Vision Access <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seychelles \u00e9 um para\u00edso natural com diversas esp\u00e9cies end\u00eamicas de plantas e animais, que o tornam um lugar \u00fanico no mundo. Um dos principais exemplos \u00e9 o coco de mer, que se tornou um s\u00edmbolo do arquip\u00e9lago e seu formato curioso pode ser encontrado desde nos mais diferentes souvenirs at\u00e9 no carimbo da imigra\u00e7\u00e3o. O [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":44512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[1436],"tags":[76,309,1583],"class_list":["post-44510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artes-cultura-diversao","tag-curiosidade","tag-praia","tag-seychelles"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles - Blog Quanto Custa Viajar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles - Blog Quanto Custa Viajar\" \/>\n<meta property=\"og:description\" content=\"Seychelles \u00e9 um para\u00edso natural com diversas esp\u00e9cies end\u00eamicas de plantas e animais, que o tornam um lugar \u00fanico no mundo. Um dos principais exemplos \u00e9 o coco de mer, que se tornou um s\u00edmbolo do arquip\u00e9lago e seu formato curioso pode ser encontrado desde nos mais diferentes souvenirs at\u00e9 no carimbo da imigra\u00e7\u00e3o. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Quanto Custa Viajar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quantocustaviajar\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-13T17:21:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-13T17:21:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o QCV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o QCV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles - Blog Quanto Custa Viajar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/","og_locale":"pt_BR","og_type":"article","og_title":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles - Blog Quanto Custa Viajar","og_description":"Seychelles \u00e9 um para\u00edso natural com diversas esp\u00e9cies end\u00eamicas de plantas e animais, que o tornam um lugar \u00fanico no mundo. Um dos principais exemplos \u00e9 o coco de mer, que se tornou um s\u00edmbolo do arquip\u00e9lago e seu formato curioso pode ser encontrado desde nos mais diferentes souvenirs at\u00e9 no carimbo da imigra\u00e7\u00e3o. O [&hellip;]","og_url":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/","og_site_name":"Blog Quanto Custa Viajar","article_publisher":"https:\/\/www.facebook.com\/quantocustaviajar","article_published_time":"2020-07-13T17:21:12+00:00","article_modified_time":"2020-07-13T17:21:20+00:00","og_image":[{"width":1020,"height":680,"url":"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o QCV","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o QCV","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#article","isPartOf":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/"},"author":{"name":"Reda\u00e7\u00e3o QCV","@id":"https:\/\/quantocustaviajar.com\/blog\/#\/schema\/person\/b99c49b1272e2104cc84a5a84122b751"},"headline":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles","datePublished":"2020-07-13T17:21:12+00:00","dateModified":"2020-07-13T17:21:20+00:00","mainEntityOfPage":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/"},"wordCount":451,"commentCount":0,"publisher":{"@id":"https:\/\/quantocustaviajar.com\/blog\/#organization"},"image":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#primaryimage"},"thumbnailUrl":"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg","keywords":["curiosidade","praia","seychelles"],"articleSection":["Artes, Cultura &amp; Divers\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/","url":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/","name":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles - Blog Quanto Custa Viajar","isPartOf":{"@id":"https:\/\/quantocustaviajar.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#primaryimage"},"image":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#primaryimage"},"thumbnailUrl":"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg","datePublished":"2020-07-13T17:21:12+00:00","dateModified":"2020-07-13T17:21:20+00:00","breadcrumb":{"@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#primaryimage","url":"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg","contentUrl":"https:\/\/quantocustaviajar.com\/blog\/wp-content\/uploads\/2020\/07\/IMG7-Female-Coco-De-Mer-Nut-bx.jpg","width":1020,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/quantocustaviajar.com\/blog\/voce-sabia-o-coco-de-mer-e-a-lenda-do-jardim-do-eden-em-seychelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/quantocustaviajar.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Voc\u00ea sabia? O coco de mer e a lenda do Jardim do \u00c9den em Seychelles"}]},{"@type":"WebSite","@id":"https:\/\/quantocustaviajar.com\/blog\/#website","url":"https:\/\/quantocustaviajar.com\/blog\/","name":"Blog Quanto Custa Viajar","description":"","publisher":{"@id":"https:\/\/quantocustaviajar.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/quantocustaviajar.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/quantocustaviajar.com\/blog\/#organization","name":"Quanto Custa Viajar","url":"https:\/\/quantocustaviajar.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/quantocustaviajar.com\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Quanto Custa Viajar"},"image":{"@id":"https:\/\/quantocustaviajar.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/quantocustaviajar"]},{"@type":"Person","@id":"https:\/\/quantocustaviajar.com\/blog\/#\/schema\/person\/b99c49b1272e2104cc84a5a84122b751","name":"Reda\u00e7\u00e3o QCV","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/quantocustaviajar.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e7b47d7a4633897697c32e0a2a1ad3abd9ca142ad0d9b7897241c6115247561b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7b47d7a4633897697c32e0a2a1ad3abd9ca142ad0d9b7897241c6115247561b?s=96&d=mm&r=g","caption":"Reda\u00e7\u00e3o QCV"},"url":"https:\/\/quantocustaviajar.com\/blog\/author\/redacao\/"}]}},"_links":{"self":[{"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/posts\/44510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/comments?post=44510"}],"version-history":[{"count":2,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/posts\/44510\/revisions"}],"predecessor-version":[{"id":44514,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/posts\/44510\/revisions\/44514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/media\/44512"}],"wp:attachment":[{"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/media?parent=44510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/categories?post=44510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quantocustaviajar.com\/blog\/wp-json\/wp\/v2\/tags?post=44510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}